{"id":46982,"date":"2023-03-10T11:00:11","date_gmt":"2023-03-10T11:00:11","guid":{"rendered":"https:\/\/parkinson.ca\/le-rapport-sur-la-sante-cerebrale-en-ontario-comprend-des-informations-sur-les-realites-de-la-maladie-de-parkinson\/"},"modified":"2025-01-21T16:29:16","modified_gmt":"2025-01-21T16:29:16","slug":"le-rapport-sur-la-sante-cerebrale-en-ontario-comprend-des-informations-sur-les-realites-de-la-maladie-de-parkinson","status":"publish","type":"post","link":"https:\/\/www.parkinson.ca\/fr\/le-rapport-sur-la-sante-cerebrale-en-ontario-comprend-des-informations-sur-les-realites-de-la-maladie-de-parkinson\/","title":{"rendered":"Le rapport sur la sant\u00e9 c\u00e9r\u00e9brale en Ontario comprend des informations sur les r\u00e9alit\u00e9s de la maladie de Parkinson"},"content":{"rendered":"<p><span data-contrast=\"none\">R\u00e9cemment, l<\/span><span data-contrast=\"none\">Institut ontarien du cerveau <\/span><span data-contrast=\"none\">a termin\u00e9 l&rsquo;\u00e9tude<\/span><a href=\"http:\/\/braininstitute.ca\/brainhealth\"><span data-contrast=\"none\">Sant\u00e9 du cerveau en Ontario<\/span><\/a><span data-contrast=\"none\">visant \u00e0 recueillir et \u00e0 diffuser des informations sur 13 troubles c\u00e9r\u00e9braux en Ontario, dont la maladie de Parkinson et les troubles du mouvement connexes.<\/span><span data-ccp-props=\"{\"134233117\":true,\"134233118\":true,\"201341983\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"none\">L&rsquo;infographie ci-dessus pr\u00e9sente des informations cl\u00e9s sur les parkinsonismes en Ontario. Le rapport complet a \u00e9t\u00e9 cr\u00e9\u00e9 \u00e0 l&rsquo;aide d&rsquo;ensembles de donn\u00e9es et de services analytiques disponibles aupr\u00e8s de l&rsquo;ICES, un organisme de recherche propre \u00e0 l&rsquo;Ontario qui recueille des donn\u00e9es sociales et de sant\u00e9 bas\u00e9es sur la population. De plus, des repr\u00e9sentants des \u00e9quipes de recherche et de d\u00e9fense des droits de Parkinson Canada ont particip\u00e9 \u00e0 l&rsquo;\u00e9laboration du rapport.    <\/span><span data-ccp-props=\"{\"134233117\":true,\"134233118\":true,\"201341983\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39812 \" src=\"https:\/\/parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-scaled.jpg\" alt=\"Infographie sur le parkinsonisme\" width=\"887\" height=\"1461\" srcset=\"https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-scaled.jpg 1554w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-182x300.jpg 182w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-425x700.jpg 425w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-91x150.jpg 91w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-768x1265.jpg 768w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-933x1536.jpg 933w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-1243x2048.jpg 1243w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-100x165.jpg 100w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-890x1466.jpg 890w, https:\/\/www.parkinson.ca\/wp-content\/uploads\/Parkinsonism_Infographic-1264x2082.jpg 1264w\" sizes=\"auto, (max-width: 887px) 100vw, 887px\" \/><\/p>\n<p><span data-contrast=\"auto\">\u00ab\u00a0Il est pr\u00e9cieux de disposer de donn\u00e9es concr\u00e8tes sur les r\u00e9alit\u00e9s de la maladie de Parkinson, notamment sur l&rsquo;utilisation des soins de sant\u00e9 et le fardeau financier\u00a0\u00bb, d\u00e9clare Maria Marano, responsable de la recherche, de l&rsquo;information et des programmes. <\/span><span data-contrast=\"none\">Les informations d\u00e9taill\u00e9es sur la maladie de Parkinson et les troubles du mouvement connexes sont limit\u00e9es.<\/span><span data-contrast=\"auto\">Les informations d\u00e9taill\u00e9es sur la sant\u00e9 concernant la maladie de Parkinson et les troubles du mouvement connexes sont limit\u00e9es, et il est formidable que des groupes de recherche recueillent des donn\u00e9es en Ontario qui peuvent \u00e9clairer notre travail \u00e0 l&rsquo;\u00e9chelle nationale. <\/span> <span data-ccp-props=\"{\"201341983\":0,\"335559739\":160,\"335559740\":259}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Le rapport complet est disponible <\/span><a href=\"http:\/\/www.braininstitute.ca\/brainhealth\"><span data-contrast=\"none\">ici<\/span><\/a><span data-contrast=\"auto\"> ainsi qu&rsquo;une page consacr\u00e9e aux <\/span><a href=\"https:\/\/braininstitute.ca\/resources\/brainhealth\/parkinsonism\"><span data-contrast=\"none\">La maladie de Parkinson en Ontario<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{\"201341983\":0,\"335559739\":160,\"335559740\":259}\"> <\/span><\/p>\n<hr>\n<p><strong>Transcription de l&rsquo;infographie :<\/strong><\/p>\n<p>Brain Health Parkinsonismes : En 2019, 44 503 Ontariens vivaient avec le Parkinsonisme et 5877 nouvelles personnes ont \u00e9t\u00e9 identifi\u00e9es cette ann\u00e9e-l\u00e0.<br \/>\nParkinsonisme selon l&rsquo;\u00e2ge et le sexe : Jeune adulte (20-39) : 1 %, adulte (40-64) : 18 %, adulte \u00e2g\u00e9 (64-74) : 28%, Personnes \u00e2g\u00e9es (75-84) : 33%, Personnes \u00e2g\u00e9es (85+) : 20%.<br \/>\nHomme : 56%, Femme : 44%.<br \/>\nTroubles c\u00e9r\u00e9braux cooccurrents : 62 % des personnes atteintes de parkinsonisme souffrent d&rsquo;un trouble c\u00e9r\u00e9bral concomitant. La d\u00e9mence, les accidents vasculaires c\u00e9r\u00e9braux et les l\u00e9sions c\u00e9r\u00e9brales sont les troubles les plus fr\u00e9quemment associ\u00e9s au parkinsonisme. Visites en sant\u00e9 mentale et en toxicomanie : Le nombre d&rsquo;hospitalisations li\u00e9es \u00e0 la sant\u00e9 mentale et \u00e0 la toxicomanie est 12 fois plus \u00e9lev\u00e9 chez les personnes atteintes de parkinsonisme que chez l&rsquo;Ontarien moyen, le nombre de visites aux urgences est 6 fois plus \u00e9lev\u00e9 chez les personnes atteintes de parkinsonisme que chez l&rsquo;Ontarien moyen, et le nombre de visites en consultation externe est 3 fois plus \u00e9lev\u00e9 chez les personnes atteintes de parkinsonisme que chez l&rsquo;Ontarien moyen. Co\u00fbt : Par rapport \u00e0 l&rsquo;Ontarien moyen, le co\u00fbt direct annuel du syst\u00e8me de sant\u00e9 est 8 fois plus \u00e9lev\u00e9 pour les personnes atteintes de parkinsonisme et 8 fois plus \u00e9lev\u00e9 pour les nouvelles personnes identifi\u00e9es comme \u00e9tant atteintes de parkinsonisme. Les donn\u00e9es de cette infographie proviennent du projet Brain Health in Ontario. Elles sont produites par l&rsquo;Institute for Clinical Evaluative Sciences et l&rsquo;Ontario Brain Institute. Pour en savoir plus sur le projet, visitez le <a href=\"http:\/\/www.braininstitute.ca\/BrainHealth\">site www.braininstitute.ca\/BrainHealth.<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9cemment, lInstitut ontarien du cerveau a termin\u00e9 l&rsquo;\u00e9tudeSant\u00e9 du cerveau en Ontariovisant \u00e0 recueillir et \u00e0 diffuser des informations sur 13 troubles c\u00e9r\u00e9braux en Ontario, dont la maladie de Parkinson et les troubles du mouvement connexes. L&rsquo;infographie ci-dessus pr\u00e9sente des informations cl\u00e9s sur les parkinsonismes en Ontario. Le rapport complet a \u00e9t\u00e9 cr\u00e9\u00e9 \u00e0 l&rsquo;aide [&hellip;]<\/p>\n","protected":false},"author":107,"featured_media":39818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[237,246],"tags":[],"audience":[],"class_list":["post-46982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogue-fr","category-recherche-blog"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/posts\/46982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/comments?post=46982"}],"version-history":[{"count":0,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/posts\/46982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/media\/39818"}],"wp:attachment":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/media?parent=46982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/categories?post=46982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/tags?post=46982"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/audience?post=46982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}