{"id":46301,"date":"2010-12-01T12:01:13","date_gmt":"2010-12-01T12:01:13","guid":{"rendered":"https:\/\/parkinson.ca\/larry-haffner-recoit-le-prix-national-du-benevolat-2\/"},"modified":"2025-01-17T22:53:03","modified_gmt":"2025-01-17T22:53:03","slug":"larry-haffner-recoit-le-prix-national-du-benevolat-2","status":"publish","type":"post","link":"https:\/\/www.parkinson.ca\/fr\/larry-haffner-recoit-le-prix-national-du-benevolat-2\/","title":{"rendered":"Larry Haffner re\u00e7oit le prix national du b\u00e9n\u00e9volat"},"content":{"rendered":"<div id=\"attachment_1560\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/parkinsonpost.files.wordpress.com\/2010\/11\/jean-pascal-souque-johanne-and-larry-haffner.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1560\" class=\"size-full wp-image-1560\" title=\"Jean Pascal Souque, Johanne et Larry Haffner.\" src=\"http:\/\/parkinsonpost.files.wordpress.com\/2010\/11\/jean-pascal-souque-johanne-and-larry-haffner.jpg\" alt=\"Jean Pascal Souque, Johanne et Larry Haffner.\" width=\"450\" height=\"300\"><\/a><p id=\"caption-attachment-1560\" class=\"wp-caption-text\">Ottawa citizen Larry Haffner awarded the David Simmonds Parkinson's Leadership Award. Jean-Pascal Souque (r) with Larry Haffner and wife Johanne.<\/p><\/div>\n<p>Larry Haffner, d&rsquo;Ottawa, a re\u00e7u le prix David Simmonds Parkinson&rsquo;s Leadership Award pour ses comp\u00e9tences extraordinaires en mati\u00e8re de leadership et pour sa contribution significative \u00e0 la vie des personnes atteintes de la maladie de Parkinson. Le prix a \u00e9t\u00e9 remis \u00e0 Ottawa, le 16 novembre 2010, par David Simmonds, qui lui a donn\u00e9 son nom. M. Haffner, qui a re\u00e7u un diagnostic de maladie de Parkinson en 1997, est l&rsquo;un des premiers \u00e0 avoir soutenu le Consortium de recherche sur la maladie de Parkinson et a g\u00e9n\u00e9r\u00e9 des fonds essentiels pour d\u00e9velopper la communaut\u00e9 canadienne de recherche sur la maladie de Parkinson \u00e0 Ottawa. Il a \u00e9galement si\u00e9g\u00e9 au conseil d&rsquo;administration de la Soci\u00e9t\u00e9 Parkinson Ottawa. \u00ab\u00a0Nous sommes ravis de remettre \u00e0 Larry Haffner le prix David Simmonds pour le leadership dans la maladie de Parkinson, car il incarne la vision, le leadership, les capacit\u00e9s de n\u00e9gociation, la pers\u00e9v\u00e9rance et l&rsquo;engagement exceptionnels qui ont renforc\u00e9 la voix des personnes vivant avec la maladie de Parkinson au Canada\u00a0\u00bb, a d\u00e9clar\u00e9 Joyce Gordon, pr\u00e9sidente-directrice g\u00e9n\u00e9rale de la Soci\u00e9t\u00e9 Parkinson Canada. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Larry Haffner, d&rsquo;Ottawa, a re\u00e7u le prix David Simmonds Parkinson&rsquo;s Leadership Award pour ses comp\u00e9tences extraordinaires en mati\u00e8re de leadership et pour sa contribution significative \u00e0 la vie des personnes atteintes de la maladie de Parkinson. Le prix a \u00e9t\u00e9 remis \u00e0 Ottawa, le 16 novembre 2010, par David Simmonds, qui lui a donn\u00e9 son [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[237],"tags":[],"audience":[],"class_list":["post-46301","post","type-post","status-publish","format-standard","hentry","category-blogue-fr"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/posts\/46301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/comments?post=46301"}],"version-history":[{"count":0,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/posts\/46301\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/media?parent=46301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/categories?post=46301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/tags?post=46301"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/www.parkinson.ca\/fr\/wp-json\/wp\/v2\/audience?post=46301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}